{"id":9888,"date":"2021-11-03T13:52:35","date_gmt":"2021-11-04T09:30:13","guid":{"rendered":"https:\/\/metmann.com.185-176-9-81.185-176-9-81.visualpublinet.com\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/"},"modified":"2023-03-22T12:52:13","modified_gmt":"2023-03-22T11:52:13","slug":"cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2","status":"publish","type":"product","link":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/","title":{"rendered":"ECO 30\/2 &#8211; Cremador de gasoil 2 etapes 142-356 kW"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div><\/div>\n<div><\/div>\n<div>\n<h3><\/h3>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>\n","protected":false},"featured_media":16234,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[]},"product_cat":[452,477],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>ECO 30\/2 - Cremador de gasoil 2 etapes 142-356 kW<\/title>\r\n<meta name=\"description\" content=\"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Cremador de gasoil 2 etapes 142-356 kW | ECO 30\/2\" \/>\r\n<meta property=\"og:description\" content=\"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MET MANN\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-03-22T11:52:13+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1578482676_6Pcq.jpg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:title\" content=\"Cremador de gasoil 2 etapes 142-356 kW | ECO 30\/2\" \/>\r\n<meta name=\"twitter:description\" content=\"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI\" \/>\r\n<meta name=\"twitter:image\" content=\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1578482676_6Pcq.jpg\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/\",\"url\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/\",\"name\":\"ECO 30\/2 - Cremador de gasoil 2 etapes 142-356 kW\",\"isPartOf\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png\",\"datePublished\":\"2021-11-04T09:30:13+00:00\",\"dateModified\":\"2023-03-22T11:52:13+00:00\",\"description\":\"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI\",\"breadcrumb\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage\",\"url\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png\",\"contentUrl\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png\",\"width\":319,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.metmann.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/www.metmann.com\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ECO 30\/2 &#8211; Cremador de gasoil 2 etapes 142-356 kW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#website\",\"url\":\"https:\/\/www.metmann.com\/ca\/\",\"name\":\"MET MANN\",\"description\":\"Climatizaci\u00f3n industrial, Calefactores y Ventilaci\u00f3n para empresas\",\"publisher\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.metmann.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#organization\",\"name\":\"Met Mann\",\"url\":\"https:\/\/www.metmann.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg\",\"contentUrl\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg\",\"width\":351,\"height\":133,\"caption\":\"Met Mann\"},\"image\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECO 30\/2 - Cremador de gasoil 2 etapes 142-356 kW","description":"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/","og_locale":"ca_ES","og_type":"article","og_title":"Cremador de gasoil 2 etapes 142-356 kW | ECO 30\/2","og_description":"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI","og_url":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/","og_site_name":"MET MANN","article_modified_time":"2023-03-22T11:52:13+00:00","og_image":[{"url":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1578482676_6Pcq.jpg"}],"twitter_card":"summary_large_image","twitter_title":"Cremador de gasoil 2 etapes 142-356 kW | ECO 30\/2","twitter_description":"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI","twitter_image":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1578482676_6Pcq.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/","url":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/","name":"ECO 30\/2 - Cremador de gasoil 2 etapes 142-356 kW","isPartOf":{"@id":"https:\/\/www.metmann.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage"},"image":{"@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png","datePublished":"2021-11-04T09:30:13+00:00","dateModified":"2023-03-22T11:52:13+00:00","description":"Cremador de gasoil | 142-356 kW | 2 etapes | ECO 30\/2 | LAMBORGHINI","breadcrumb":{"@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#primaryimage","url":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png","contentUrl":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/11\/ECO-15\uf0222_20\u00b72_22\u00b72_30\u00b72_40\u00b72.png","width":319,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/www.metmann.com\/ca\/producto\/cremador-de-gasoil-2-etapes-142-356-kw-eco-30-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.metmann.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.metmann.com\/productos\/"},{"@type":"ListItem","position":3,"name":"ECO 30\/2 &#8211; Cremador de gasoil 2 etapes 142-356 kW"}]},{"@type":"WebSite","@id":"https:\/\/www.metmann.com\/ca\/#website","url":"https:\/\/www.metmann.com\/ca\/","name":"MET MANN","description":"Climatizaci\u00f3n industrial, Calefactores y Ventilaci\u00f3n para empresas","publisher":{"@id":"https:\/\/www.metmann.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metmann.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.metmann.com\/ca\/#organization","name":"Met Mann","url":"https:\/\/www.metmann.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg","contentUrl":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg","width":351,"height":133,"caption":"Met Mann"},"image":{"@id":"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product\/9888"}],"collection":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/comments?post=9888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/media\/16234"}],"wp:attachment":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/media?parent=9888"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product_cat?post=9888"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product_tag?post=9888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}