{"id":465,"count":7,"description":"","link":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/","name":"Cremadors de gasoil UNIGAS de 25 a 560 kW 2 etapes","slug":"cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes","taxonomy":"product_cat","parent":452,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes<\/title>\r\n<meta name=\"description\" content=\"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/\" \/>\r\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes\" \/>\r\n<meta property=\"og:description\" content=\"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/\" \/>\r\n<meta property=\"og:site_name\" content=\"MET MANN\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1575898162_W1e9.jpg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:title\" content=\"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes\" \/>\r\n<meta name=\"twitter:description\" content=\"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS\" \/>\r\n<meta name=\"twitter:image\" content=\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1575898162_W1e9.jpg\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/\",\"url\":\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/\",\"name\":\"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes\",\"isPartOf\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#website\"},\"description\":\"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS\",\"breadcrumb\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.metmann.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cremadors de gas o gasoil\",\"item\":\"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cremadors de gasoil UNIGAS de 25 a 560 kW 2 etapes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#website\",\"url\":\"https:\/\/www.metmann.com\/ca\/\",\"name\":\"MET MANN\",\"description\":\"Climatizaci\u00f3n industrial, Calefactores y Ventilaci\u00f3n para empresas\",\"publisher\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.metmann.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#organization\",\"name\":\"Met Mann\",\"url\":\"https:\/\/www.metmann.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg\",\"contentUrl\":\"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg\",\"width\":351,\"height\":133,\"caption\":\"Met Mann\"},\"image\":{\"@id\":\"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes","description":"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/","og_locale":"ca_ES","og_type":"article","og_title":"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes","og_description":"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS","og_url":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/","og_site_name":"MET MANN","og_image":[{"url":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1575898162_W1e9.jpg"}],"twitter_card":"summary_large_image","twitter_title":"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes","twitter_description":"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS","twitter_image":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/09\/1575898162_W1e9.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/","url":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/","name":"Cremadors de gasoil UNIGAS de 25 a 560 kW de 2 etapes","isPartOf":{"@id":"https:\/\/www.metmann.com\/ca\/#website"},"description":"Cremadors de gasoil | 2 etapes | 14-560 kW | UNIGAS","breadcrumb":{"@id":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/cremadors-de-gasoil-unigas-de-25-a-560-kw-de-2-etapes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.metmann.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Cremadors de gas o gasoil","item":"https:\/\/www.metmann.com\/ca\/categoria-producto\/cremadors-de-gas-o-gasoil\/"},{"@type":"ListItem","position":3,"name":"Cremadors de gasoil UNIGAS de 25 a 560 kW 2 etapes"}]},{"@type":"WebSite","@id":"https:\/\/www.metmann.com\/ca\/#website","url":"https:\/\/www.metmann.com\/ca\/","name":"MET MANN","description":"Climatizaci\u00f3n industrial, Calefactores y Ventilaci\u00f3n para empresas","publisher":{"@id":"https:\/\/www.metmann.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metmann.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.metmann.com\/ca\/#organization","name":"Met Mann","url":"https:\/\/www.metmann.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg","contentUrl":"https:\/\/www.metmann.com\/wp-content\/uploads\/2021\/12\/logo-color-met-mann-01.jpg","width":351,"height":133,"caption":"Met Mann"},"image":{"@id":"https:\/\/www.metmann.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product_cat\/465"}],"collection":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product_cat\/452"}],"wp:post_type":[{"href":"https:\/\/www.metmann.com\/ca\/wp-json\/wp\/v2\/product?product_cat=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}